{"id":2156,"date":"2019-06-11T15:43:08","date_gmt":"2019-06-11T21:43:08","guid":{"rendered":"https:\/\/wellbridge.com\/sports-and-wellness-del-norte\/?page_id=2156"},"modified":"2025-02-18T09:51:10","modified_gmt":"2025-02-18T16:51:10","slug":"personal-training","status":"publish","type":"page","link":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/","title":{"rendered":"Personal Training at Colorado Athletic Club \u2013 DTC"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":68,"featured_media":0,"parent":302,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2156","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personal Fitness Training in Greenwood Village, CO<\/title>\n<meta name=\"description\" content=\"Colorado Athletic Club DTC offers personal training services tailored to your fitness needs. Start your health journey with us today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personal Fitness Training in Greenwood Village, CO\" \/>\n<meta property=\"og:description\" content=\"Colorado Athletic Club DTC offers personal training services tailored to your fitness needs. Start your health journey with us today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/\" \/>\n<meta property=\"og:site_name\" content=\"Colorado Athletic Club - DTC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CACDenverTechCenter\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T16:51:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cacdtc\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/fitness\\\/training\\\/personal-training\\\/\",\"url\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/fitness\\\/training\\\/personal-training\\\/\",\"name\":\"Personal Fitness Training in Greenwood Village, CO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/#website\"},\"datePublished\":\"2019-06-11T21:43:08+00:00\",\"dateModified\":\"2025-02-18T16:51:10+00:00\",\"description\":\"Colorado Athletic Club DTC offers personal training services tailored to your fitness needs. Start your health journey with us today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/fitness\\\/training\\\/personal-training\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/fitness\\\/training\\\/personal-training\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/fitness\\\/training\\\/personal-training\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fitness\",\"item\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/fitness\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Training\",\"item\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/fitness\\\/training\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Personal Training at Colorado Athletic Club \u2013 DTC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/#website\",\"url\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/\",\"name\":\"Colorado Athletic Club - DTC\",\"description\":\"Wellbridge, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wellbridge.com\\\/colorado-athletic-club-dtc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personal Fitness Training in Greenwood Village, CO","description":"Colorado Athletic Club DTC offers personal training services tailored to your fitness needs. Start your health journey with us today.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/","og_locale":"en_US","og_type":"article","og_title":"Personal Fitness Training in Greenwood Village, CO","og_description":"Colorado Athletic Club DTC offers personal training services tailored to your fitness needs. Start your health journey with us today.","og_url":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/","og_site_name":"Colorado Athletic Club - DTC","article_publisher":"https:\/\/www.facebook.com\/CACDenverTechCenter","article_modified_time":"2025-02-18T16:51:10+00:00","twitter_card":"summary_large_image","twitter_site":"@cacdtc","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/","url":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/","name":"Personal Fitness Training in Greenwood Village, CO","isPartOf":{"@id":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/#website"},"datePublished":"2019-06-11T21:43:08+00:00","dateModified":"2025-02-18T16:51:10+00:00","description":"Colorado Athletic Club DTC offers personal training services tailored to your fitness needs. Start your health journey with us today.","breadcrumb":{"@id":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/personal-training\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/"},{"@type":"ListItem","position":2,"name":"Fitness","item":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/"},{"@type":"ListItem","position":3,"name":"Training","item":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/fitness\/training\/"},{"@type":"ListItem","position":4,"name":"Personal Training at Colorado Athletic Club \u2013 DTC"}]},{"@type":"WebSite","@id":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/#website","url":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/","name":"Colorado Athletic Club - DTC","description":"Wellbridge, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/wp-json\/wp\/v2\/pages\/2156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/wp-json\/wp\/v2\/comments?post=2156"}],"version-history":[{"count":0,"href":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/wp-json\/wp\/v2\/pages\/2156\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/wp-json\/wp\/v2\/pages\/302"}],"wp:attachment":[{"href":"https:\/\/wellbridge.com\/colorado-athletic-club-dtc\/wp-json\/wp\/v2\/media?parent=2156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}